{"id":2253,"date":"2024-04-10T13:39:44","date_gmt":"2024-04-10T11:39:44","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2253"},"modified":"2025-08-29T12:14:48","modified_gmt":"2025-08-29T10:14:48","slug":"proyecto-taxotic-2019","status":"publish","type":"page","link":"https:\/\/computaex.es\/en\/proyectos\/proyecto-taxotic-2019\/","title":{"rendered":"TaxoTIC 2019"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<ul>\n<li>Equipo de <a href=\"\/en\/\">COMPUTAEX<\/a>.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan ser analizadas en profundidad. El proyecto TaxoTIC se inici\u00f3 en el a\u00f1o 2013 con el objetivo de visibilizar las TIC y a aquellas empresas y profesionales de Extremadura que prestan servicios relacionados con las mismas.<\/p>\n<p>El trabajo realizado desde el a\u00f1o 2013 ha permitido el desarrollo de un observatorio del Sector TIC en la regi\u00f3n, en el que se incluye informaci\u00f3n de las empresas y profesionales del sector, as\u00ed como de la formaci\u00f3n TIC profesional y universitaria. Durante el a\u00f1o 2013 se identificaron y clasificaron aquellas actividades que, desde el punto de vista del equipo de C\u00e9nitS, podr\u00edan ser consideradas TIC. Partiendo de dicha clasificaci\u00f3n, se identific\u00f3 y caracteriz\u00f3 el sector, analizando todas las posibles empresas cuyas actividades principales estuvieran entre las establecidas como TIC para, finalmente, analizar el sector en Extremadura desde un punto de vista interno y externo (compar\u00e1ndolo con otros sectores m\u00e1s tradicionales de la regi\u00f3n).<\/p>\n<p>En 2014 se analiz\u00f3 el sector TIC en Espa\u00f1a y Europa para ver las diferencias existentes con Extremadura. Adem\u00e1s, se dise\u00f1\u00f3 y desarroll\u00f3 la plataforma OpenData OLISTIC (Observatorio regionaL de Informaci\u00f3n del Sector TIC) que contiene informaci\u00f3n de las empresas que componen el sector y las actividades TIC que desempe\u00f1an. Finalmente, con el fin de entender mejor el sector, se realiz\u00f3 un estudio desde el punto de vista de los directivos de las empresas TIC, con una encuesta y una serie de entrevistas a directivos de car\u00e1cter regional y nacional.<\/p>\n<p>En 2015 se realiz\u00f3 la automatizaci\u00f3n de ciertas actividades asociadas al proyecto, como son la detecci\u00f3n de constituciones y disoluciones de sociedades y se desarrollaron nuevas aplicaciones para la plataforma Opendata. De nuevo, con el fin de analizar el sector desde todos los puntos de vista posibles, se realiz\u00f3 un estudio del equipamiento y uso de las TIC en Extremadura, ofreciendo de este modo una visi\u00f3n de las TIC m\u00e1s orientada a sus usuarios finales.<\/p>\n<p>En 2016 se a\u00f1adi\u00f3 a la plataforma OLISTIC informaci\u00f3n sobre los perfiles profesionales TIC y sus competencias asociadas. Para su elaboraci\u00f3n se utiliz\u00f3 como referencia el e-CF (European e-Competence Framework) que en 2016 se transform\u00f3 en un est\u00e1ndar europeo y que fue publicado oficialmente como la norma EN 16234-1. El marco e-CF define 23 perfiles profesionales y 40 competencias. En el momento de la elaboraci\u00f3n del proyecto no se contaba con ninguna traducci\u00f3n oficial del mismo al castellano y \u00e9sta fue realizada, en el marco del proyecto, por los propios t\u00e9cnicos de C\u00e9nitS.<\/p>\n<p>En 2017 se decidi\u00f3 ampliar la informaci\u00f3n relacionada con la formaci\u00f3n TIC en la regi\u00f3n incluyendo la formaci\u00f3n profesional. La formaci\u00f3n profesional que est\u00e1 adquiriendo mayor protagonismo en\u00a0los \u00faltimos a\u00f1os y la incorporaci\u00f3n de la misma al estudio permite establecer una foto m\u00e1s precisa de los profesionales TIC que se forman cada a\u00f1o en la regi\u00f3n.<\/p>\n<p>La Fundaci\u00f3n COMPUTAEX considera que la informaci\u00f3n aportada por el proyecto es importante para Extremadura y, sobre todo, para el propio Sector TIC. Por ello, durante los a\u00f1os 2018 y 2019, ha continuado la labor de recopilaci\u00f3n y an\u00e1lisis de toda la informaci\u00f3n relevante para el Sector TIC regional.<\/p>\n<p>La novedad m\u00e1s significativa aportada durante el a\u00f1o 2019 ha sido la actualizaci\u00f3n de la documentaci\u00f3n en castellano de la norma europea CEN Workshop Agreement CWA 16458-1:2018. Esta norma es de especial inter\u00e9s para el proyecto, ya que se trata de la segunda versi\u00f3n de la descripci\u00f3n de perfiles profesionales TIC europeos y en ella se presentan modificaciones a algunos de los 23 perfiles ya existentes (traducidos y analizados en el a\u00f1o 2016 en el seno de este proyecto) y se proponen siete nuevos perfiles relacionados, principalmente, con la proliferaci\u00f3n de la an\u00e1litica de datos y las metodolog\u00edas \u00e1giles de desarrollo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Actualizaci\u00f3n de la informaci\u00f3n recopilada desde el comienzo del proyecto sobre el sector regional, nacional y europeo.<\/li>\n<li>Integraci\u00f3n de la informaci\u00f3n del proyecto en una \u00fanica plataforma (OLISTIC).<\/li>\n<li>Elaboraci\u00f3n de informes y obtenci\u00f3n de conclusiones de la taxonom\u00eda del Sector TIC y su proyecci\u00f3n para el futuro.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-metodologia field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Metodolog\u00eda:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>En primer lugar, se procede a la actualizaci\u00f3n de la informaci\u00f3n del Sector TIC regional a con informaci\u00f3n extra\u00edda de la propia plataforma del proyecto (OLISTIC) y del Instituto Nacional de Estad\u00edstica (INE). De este modo se obtienen estad\u00edsticas econ\u00f3micas y de sociedades del sector en Extremadura. A continuaci\u00f3n, se actualiza la informaci\u00f3n relativa a la formaci\u00f3n TIC en la regi\u00f3n y en Espa\u00f1a. Los datos son extra\u00eddos principalmente del Observatorio de Indicadores de la Universidad de Extremadura y de las Estad\u00edsticas de la Educaci\u00f3n del Ministerio de Educaci\u00f3n y Formaci\u00f3n Profesional. Una vez recopilados los datos, se realiza un an\u00e1lisis de los datos econ\u00f3micos del Sector TIC en Extremadura mediante una comparativa econ\u00f3mica con otros sectores productivos m\u00e1s tradicionales en la regi\u00f3n. El an\u00e1lisis se completa con una comparativa del sector regional respecto al sector nacional y europeo.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos-alcanzados field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objetivos alcanzados:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Disposici\u00f3n de informaci\u00f3n econ\u00f3mica, empresarial y de formaci\u00f3n actualizada del Sector TIC en Extremadura.<\/li>\n<li>An\u00e1lisis actualizado del Sector TIC en Espa\u00f1a y Europa y comparativa con el sector en Extremadura.<\/li>\n<li>Actualizaci\u00f3n del contenido de la plataforma OLISTIC.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-publicaciones field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Publicaciones y congresos:\u00a0<\/strong><\/div>\n<div><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p><strong><img decoding=\"async\" style=\"width: 3%; float: left;\" src=\"\/wp-content\/uploads\/2025\/01\/icono-pdf.png\" alt=\"\" \/>\u00a0Memorias anuales del<br \/>\nproyecto TaxonomTIC<\/strong>:\u00a0\u00a0<strong><a href=\"http:\/\/www.cenits.es\/sites\/cenits.es\/files\/publicaciones\/memoria-taxonomtic-2013.pdf\" target=\"_blank\" rel=\"noopener\">2013<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.cenits.es\/sites\/cenits.es\/files\/publicaciones\/taxonomtic_2014_memoria.pdf\" target=\"_blank\" rel=\"noopener\">2014<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.cenits.es\/sites\/cenits.es\/files\/noticias\/taxonomtic_2015_memoria.pdf\" target=\"_blank\" rel=\"noopener\">2015<\/a>\u00a0&#8211; <a href=\"http:\/\/www.cenits.es\/wp-content\/uploads\/2025\/01\/memoria_taxonomtic_2016.pdf\" target=\"_blank\" rel=\"noopener\">2016<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.cenits.es\/wp-content\/uploads\/2025\/01\/memoria_taxonomtic_2017.pdf\" target=\"_blank\" rel=\"noopener\">2017<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.cenits.es\/wp-content\/uploads\/2025\/01\/memoria_taxonomtic_2018.pdf\" target=\"_blank\" rel=\"noopener\">2018<\/a>\u00a0&#8211;\u00a0<a href=\"http:\/\/www.cenits.es\/sites\/cenits.es\/files\/noticias\/memoria_taxotic_2019.pdf\" target=\"_blank\" rel=\"noopener\">2019<\/a><\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-taxonomy-vocabulary-4 field-type-taxonomy-term-reference field-label-hidden\">\n<div class=\"field-items\">\n<div style=\"text-align: justify;\"><\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Equipo de COMPUTAEX. Descripci\u00f3n:\u00a0 Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[104,81],"tags":[],"class_list":["post-2253","page","type-page","status-publish","hentry","category-ciencias-informaticas-y-de-comunicaciones","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-taxotic-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Equipo de COMPUTAEX. Descripci\u00f3n:\u00a0 Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-taxotic-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:14:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-taxotic-2019\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-taxotic-2019\\\/\",\"name\":\"TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-10T11:39:44+00:00\",\"dateModified\":\"2025-08-29T10:14:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-taxotic-2019\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-taxotic-2019\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-taxotic-2019\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"TaxoTIC 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/proyectos\/proyecto-taxotic-2019\/","og_locale":"en_US","og_type":"article","og_title":"TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Equipo de COMPUTAEX. Descripci\u00f3n:\u00a0 Las Tecnolog\u00edas de la Informaci\u00f3n y las Comunicaciones (TIC) se han convertido en el principal motor de la emergente econom\u00eda digital y, como tal, merec\u00edan ...","og_url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-taxotic-2019\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T10:14:48+00:00","og_image":[{"width":1024,"height":403,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-taxotic-2019\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-taxotic-2019\/","name":"TaxoTIC 2019 - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-10T11:39:44+00:00","dateModified":"2025-08-29T10:14:48+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-taxotic-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-taxotic-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-taxotic-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"TaxoTIC 2019"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2253"}],"version-history":[{"count":10,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2253\/revisions"}],"predecessor-version":[{"id":8549,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2253\/revisions\/8549"}],"up":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}