{"id":2286,"date":"2024-04-10T13:46:12","date_gmt":"2024-04-10T11:46:12","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2286"},"modified":"2025-08-29T11:56:41","modified_gmt":"2025-08-29T09:56:41","slug":"proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios","status":"publish","type":"page","link":"https:\/\/computaex.es\/en\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/","title":{"rendered":"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\"><strong>Researchers:<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li><a href=\"\/en\/\">COMPUTAEX<\/a>.<\/li>\n<li><a href=\"https:\/\/\/en\/casat.es\/\">CASAT<\/a>.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\">\n<div class=\"field-label\"><strong>Description:<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>El objetivo general del proyecto\u00a0<a href=\"\/en\/proyectos\/proyecto-cultivdata\/\" target=\"_blank\" rel=\"noopener\">CultivData<\/a>\u00a0est\u00e1 centrado en el an\u00e1lisis, dise\u00f1o y pilotaje de un prototipo de plataforma inform\u00e1tica para el \u201ccultivo\u201d de datos agrarios abiertos y p\u00fablicos aspirando a la excelencia en el sector agrario extreme\u00f1o. La plataforma capta datos de muy diversas fuentes y formatos para, una vez obtenidos, aplicar t\u00e9cnicas de Big Data con el fin de crear modelos de datos que permitan obtener conocimiento que pueda resultar de utilidad para los grupos de inter\u00e9s del sector agroalimentario. Este conocimiento permitir\u00e1 tomar decisiones fundamentales para mejorar la calidad de los productos, ampliar la productividad de las explotaciones y aspirar a la eficiencia en la comercializaci\u00f3n.<\/p>\n<p>Se est\u00e1 obteniendo en CultivData una metodolog\u00eda y un prototipo en el que las t\u00e9cnicas anal\u00edticas de Big Data son un requerimiento muy importante, dados los vol\u00famenes de datos y variantes de formatos. La velocidad de respuesta y las simulaciones casi en tiempo real requieren de la potencia de procesamiento HPC (High Performance Computing) que el supercomputador\u00a0<a href=\"\/en\/lusitania\/lusitania-II\/\">LUSITANIA II<\/a>\u00a0puede aportar a este tipo de proyectos.<\/p>\n<p>CultivDat2 se propone como nueva versi\u00f3n evolucionada y ampliada de CultivData que se enriquecer\u00e1 con la propuesta de modelos predictivos basados en t\u00e9cnicas computacionales y de inteligencia artificial garantizando la seguridad de la informaci\u00f3n y generando modelos matem\u00e1ticos que ejecutados en el supercomputador LUSITANIA den respuesta a sus usuarios en el menor tiempo posible. El proyecto CultivDat2 propone la convergencia de tecnolog\u00edas puestas al servicio del sector agrario para producir de forma inteligente y sostenible con la calidad tradicional y bas\u00e1ndonos en la experiencia del pasado, el conocimiento del presente y usando la predictibilidad del futuro.<\/p>\n<p>CultivDat2 incorporar\u00e1 a la plataforma CultivData nuevas fuentes de datos provenientes de im\u00e1genes satelitales, de composiciones de suelos y de caracter\u00edsticas de aguas de riegos que aporten a la plataforma un enriquecimiento de la informaci\u00f3n almacenada, procesada y analizada. Esto permitir\u00e1 incorporar mayor cantidad de informaci\u00f3n y datos hist\u00f3ricos, que es los m\u00e1s importante para que la capacidad predictiva, a trav\u00e9s de la ciencia de datos, pueda dar un paso m\u00e1s en la estad\u00edstica agraria y desarrollar modelos predictivos para el cultivo de datos que faciliten la toma de decisiones y la aplicaci\u00f3n de agricultura de precisi\u00f3n.<\/p>\n<p>Para llevar a cabo CultivDat2, se contempla la incorporaci\u00f3n de un estudiante trabajador, teniendo en cuenta la mejora y adquisici\u00f3n de competencias y capacidades para el desempe\u00f1o como tecn\u00f3logo de las actividades descritas en el proyecto, comprendidas en la l\u00ednea estrat\u00e9gica del sector agroalimentario, unida a la l\u00ednea estrat\u00e9gica de las tecnolog\u00edas inform\u00e1ticas y de las comunicaciones.<\/p>\n<p>Este proyecto de investigaci\u00f3n se encuentra encuadrado en la l\u00ednea estrat\u00e9gica de Agroalimentaci\u00f3n, definida en el VI Plan Regional de Investigaci\u00f3n, Desarrollo Tecnol\u00f3gico e Innovaci\u00f3n 2017-2020, aprobado mediante Decreto 91\/2017, de 20 junio (DOE n.o 121, de 26 de junio).<\/p>\n<p><strong>Sources of funding:<\/strong><\/p>\n<ul>\n<li>Proyecto cofinanciado por la\u00a0<a href=\"http:\/\/www.juntaex.es\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/\/www.juntaex.es\">Regional Government of Extremadura<\/a>,\u00a0<a href=\"http:\/\/www.juntaex.es\/con04\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/\/www.juntaex.es\/con04\/\">Consejer\u00eda de Educaci\u00f3n y Empleo<\/a>&#8211;<a href=\"http:\/\/\/en\/extremaduratrabaja.juntaex.es\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/extremaduratrabaja.juntaex.es\/\">SEXPE<\/a>\u00a0y el\u00a0<a href=\"http:\/\/\/en\/ec.europa.eu\/esf\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/ec.europa.eu\/esf\/\">Fondo Social Europeo<\/a>, a trav\u00e9s de la convocatoria de ayudas destinadas al fomento de la contrataci\u00f3n de personal de apoyo a la investigaci\u00f3n en la comunidad aut\u00f3noma de Extremadura (<a href=\"http:\/\/\/en\/doe.juntaex.es\/pdfs\/doe\/2019\/1910o\/19062241.pdf\/\" target=\"_blank\" rel=\"noopener\" data-cke-saved-href=\"http:\/doe.juntaex.es\/pdfs\/doe\/2019\/1910o\/19062241.pdf\">Resoluci\u00f3n de 6 de septiembre de 2019<\/a>).<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><center><img decoding=\"async\" style=\"width: 150px; height: 80px;\" src=\"\/wp-content\/uploads\/2025\/01\/logo-sexpe.jpg\" alt=\"\" \/>\u00a0 \u00a0 \u00a0\u00a0<img decoding=\"async\" style=\"width: 300px; height: 60px;\" src=\"\/wp-content\/uploads\/2025\/01\/logo-consejeria-educacion-empleo.png\" alt=\"\" \/>\u00a0 \u00a0 \u00a0<img decoding=\"async\" style=\"width: 265px; height: 80px;\" src=\"\/wp-content\/uploads\/2025\/01\/logo-fse-iej.png\" alt=\"\" \/><\/center><\/p>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\">\n<div class=\"field-items\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores: COMPUTAEX. CASAT. Descripci\u00f3n: El objetivo general del proyecto\u00a0CultivData\u00a0est\u00e1 centrado en el an\u00e1lisis, dise\u00f1o y pilotaje de un prototipo de plataforma inform\u00e1tica para el \u201ccultivo\u201d de datos agrarios abiertos y &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[103,81],"tags":[],"class_list":["post-2286","page","type-page","status-publish","hentry","category-ciencias-de-la-vida","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores: COMPUTAEX. CASAT. Descripci\u00f3n: El objetivo general del proyecto\u00a0CultivData\u00a0est\u00e1 centrado en el an\u00e1lisis, dise\u00f1o y pilotaje de un prototipo de plataforma inform\u00e1tica para el \u201ccultivo\u201d de datos agrarios abiertos y ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T09:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\\\/\",\"name\":\"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-10T11:46:12+00:00\",\"dateModified\":\"2025-08-29T09:56:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/","og_locale":"en_US","og_type":"article","og_title":"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores: COMPUTAEX. CASAT. Descripci\u00f3n: El objetivo general del proyecto\u00a0CultivData\u00a0est\u00e1 centrado en el an\u00e1lisis, dise\u00f1o y pilotaje de un prototipo de plataforma inform\u00e1tica para el \u201ccultivo\u201d de datos agrarios abiertos y ...","og_url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T09:56:41+00:00","og_image":[{"width":1024,"height":403,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/","name":"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-10T11:46:12+00:00","dateModified":"2025-08-29T09:56:41+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-cultivdat2-desarrollo-sostenible-aplicando-modelos-predictivos-al-cultivo-de-datos-agrarios\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"CultivDat2: Desarrollo sostenible aplicando modelos predictivos al cultivo de datos agrarios"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2286"}],"version-history":[{"count":7,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2286\/revisions"}],"predecessor-version":[{"id":8372,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2286\/revisions\/8372"}],"up":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}