{"id":2402,"date":"2024-04-11T08:44:30","date_gmt":"2024-04-11T06:44:30","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2402"},"modified":"2025-08-29T12:13:31","modified_gmt":"2025-08-29T10:13:31","slug":"proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones","status":"publish","type":"page","link":"https:\/\/computaex.es\/en\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/","title":{"rendered":"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<ul>\n<li>Juan Antonio Rico Gallego (Investigador Principal). Universidad de Extremadura.<\/li>\n<li>Juan Carlos D\u00edaz Mart\u00edn. Universidad de Extremadura.<\/li>\n<li>Juan Luis Garc\u00eda Zapata. Universidad de Extremadura.<\/li>\n<li>Javier Corral Garc\u00eda. Fundaci\u00f3n COMPUTAEX.<\/li>\n<li>Jes\u00fas Calle Cancho. Fundaci\u00f3n COMPUTAEX.<\/li>\n<li>Carmen Calvo Jurado. Universidad de Extremadura.<\/li>\n<li>Jes\u00fas \u00c1lvarez Llorente. Universidad de Extremadura.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>Los sistemas hardware utilizados en computaci\u00f3n paralela de altas prestaciones son heterog\u00e9neos. Centros de c\u00e1lculo y grandes instalaciones han incorporado m\u00e1quinas que combinan procesadores multi-core y aceleradores (GPUs, etc.) conectados mediantes diferentes canales de comunicaci\u00f3n, fundamentalmente memoria compartida y redes de altas prestaciones como Infinband. El objetivo de esta propuesta es doble: incrementar el rendimiento de supercomputaci\u00f3n actual, crecientemente heterog\u00e9nea, y al mismo tiempo reducir su consumo energ\u00e9tico.<\/p>\n<p>Las aplicaciones que ejecutan en estas plataformas lo hacen usualmente en una secuencia de fases de computaci\u00f3n y comunicaci\u00f3n. El c\u00f3digo de las mismas est\u00e1 compuesto por una serie de patrones o kernels, como por ejemplo una multiplicaci\u00f3n de matrices o una trasformada de Fourier. Estos kernels son ejecutados de forma paralela por procesos que ejecutan sobre hardware heterog\u00e9neo, y por tanto, con diferentes capacidades de c\u00f3mputo. En el actual estado del arte, el tiempo de ejecuci\u00f3n del kernel se optimiza mediante una distribuci\u00f3n no uniforme de la carga de c\u00f3mputo, asignando a cada proceso el trabajo que pueda realizar de forma que la carga global quede equilibrada, a fin de que todos los procesos lleguen a la vez a la fase de comunicaci\u00f3n de resultados, evitando que los m\u00e1s r\u00e1pidos esperen a los m\u00e1s lentos.<\/p>\n<p>En los sistemas heterog\u00e9neos que encontramos en las instalaciones actuales de supercomputaci\u00f3n, el criterio de equilibrado basado en la carga es necesario pero es insuficiente, y esta es la cuesti\u00f3n que acomete la propuesta. El problema es ahora bien conocido y comienza a ser objeto de atenci\u00f3n por parte de la comunidad investigadora. La distribuci\u00f3n no uniforme de la carga de trabajo no s\u00f3lo produce diferencias en el volumen de datos que cada proceso transmite, sino que tambi\u00e9n determina la utilizaci\u00f3n de los diferentes canales de comunicaci\u00f3n del sistema.<\/p>\n<p>En consecuencia, encontrar una asignaci\u00f3n de carga \u00f3ptima, exige no s\u00f3lo conocer la capacidad de carga de los procesadores implicados, sino tambi\u00e9n estimar el coste de las comunicaciones derivado de cada asignaci\u00f3n. Si actualmente la b\u00fasqueda de la mejor configuraci\u00f3n se hace a trav\u00e9s de costosos tests que hacen un uso extensivo de los recursos de c\u00f3mputo del sistema, en este proyecto se propone la utilizaci\u00f3n de un modelo anal\u00edtico de predicci\u00f3n de coste de comunicaciones desarrollado en la Universidad de Extremadura (UEX) y el University College de Dublin (UCD) de Irlanda. El modelo se denomina \u03c4-Lop. Evaluado en clusters multi-core con redes de altas prestaciones, \u03c4-Lop ha sido publicado en dos revistas de reconocido prestigio (primer cuartil y primer decil), y ha sido objeto de una tesis doctoral con menci\u00f3n europea en la UEX. La propuesta busca financiaci\u00f3n para extenderlo a plataformas heterog\u00e9neas. Consideramos que la aproximaci\u00f3n basada en \u03c4-Lop posibilitar\u00e1 automatizar el proceso de asignaci\u00f3n \u00f3ptima de carga en arquitecturas heterog\u00e9neas, evitando el consumo intensivo de recursos que requieren los tests, y obteniendo una mejora significativa del rendimiento durante la ejecuci\u00f3n de la aplicaci\u00f3n. Ello redundar\u00e1 en el ahorro apreciable de costes tanto computacionales como energ\u00e9ticos en las instalaciones de supercomputaci\u00f3n.<\/p>\n<p>El objetivo \u00faltimo del proyecto, no obstante, es eminentemente pr\u00e1ctico. Consiste en el desarrollo de una herramienta de usuario que proponga una distribuci\u00f3n de carga teniendo en cuenta los modelos computacional y de comunicaciones de la aplicaci\u00f3n. La integraci\u00f3n de ambos modelos es la parte central de la propuesta. Supondr\u00eda el primer modelo de estas caracter\u00edsticas que no solo puede ser usado en aras del rendimiento y el consumo energ\u00e9tico, sino en simuladores y algoritmos de optimizaci\u00f3n.<\/p>\n<p>La propuesta parte del trabajo realizado por el investigador principal en el desarrollo de su tesis doctoral. Cuenta con un equipo multidisciplinar que incluye expertos de diferentes campos, y trabaja habitualmente con investigadores nacionales e internacionales para afrontar un proyecto con dos hitos principales, el desarrollo de un modelo formal mixto de asignaci\u00f3n de carga, y su posterior aplicaci\u00f3n en forma de una herramienta software usable por el usuario final de un centro de supercomputaci\u00f3n.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-financiacion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Sources of funding:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Proyecto cofinanciado por la Junta de Extremadura y el Fondo Europeo de Desarrollo Regional (FEDER) de Extremadura al 80 %, dentro del Objetivo Tem\u00e1tico 01 \u201cRefuerzo de la investigaci\u00f3n, el desarrollo tecnol\u00f3gico y la innovaci\u00f3n\u201d, a trav\u00e9s de la convocatoria de ayudas destinadas a la realizaci\u00f3n de proyectos de investigaci\u00f3n, orientados hacia las \u00e1reas estrat\u00e9gicas de la econom\u00eda regional contempladas en el V Plan Regional de I+D+i (2014-2017), en los centros p\u00fablicos de I+D+i de la Comunidad Aut\u00f3noma de Extremadura, al amparo del Decreto 68\/2016 de 6 de junio.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-taxonomy-vocabulary-4 field-type-taxonomy-term-reference field-label-hidden\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Juan Antonio Rico Gallego (Investigador Principal). Universidad de Extremadura. Juan Carlos D\u00edaz Mart\u00edn. Universidad de Extremadura. Juan Luis Garc\u00eda Zapata. Universidad de Extremadura. Javier Corral Garc\u00eda. Fundaci\u00f3n COMPUTAEX. Jes\u00fas &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[104,81],"tags":[],"class_list":["post-2402","page","type-page","status-publish","hentry","category-ciencias-informaticas-y-de-comunicaciones","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Juan Antonio Rico Gallego (Investigador Principal). Universidad de Extremadura. Juan Carlos D\u00edaz Mart\u00edn. Universidad de Extremadura. Juan Luis Garc\u00eda Zapata. Universidad de Extremadura. Javier Corral Garc\u00eda. Fundaci\u00f3n COMPUTAEX. Jes\u00fas ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:13:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\\\/\",\"name\":\"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-11T06:44:30+00:00\",\"dateModified\":\"2025-08-29T10:13:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/","og_locale":"en_US","og_type":"article","og_title":"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Juan Antonio Rico Gallego (Investigador Principal). Universidad de Extremadura. Juan Carlos D\u00edaz Mart\u00edn. Universidad de Extremadura. Juan Luis Garc\u00eda Zapata. Universidad de Extremadura. Javier Corral Garc\u00eda. Fundaci\u00f3n COMPUTAEX. Jes\u00fas ...","og_url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T10:13:31+00:00","og_image":[{"width":1024,"height":403,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/","name":"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-11T06:44:30+00:00","dateModified":"2025-08-29T10:13:31+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-optimizacion-de-algoritmos-y-aplicaciones-paralelas-en-sistemas-heterogeneos-mediante-el-uso-combinado-de-modelos-formales-de-computo-y-comunicaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Optimizaci\u00f3n de Algoritmos y Aplicaciones Paralelas en Sistemas Heterog\u00e9neos Mediante el Uso Combinado de Modelos Formales de C\u00f3mputo y Comunicaciones"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2402"}],"version-history":[{"count":5,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2402\/revisions"}],"predecessor-version":[{"id":8512,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2402\/revisions\/8512"}],"up":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}