{"id":2683,"date":"2024-04-11T09:54:35","date_gmt":"2024-04-11T07:54:35","guid":{"rendered":"http:\/\/10.128.3.28\/?page_id=2683"},"modified":"2025-08-29T12:14:33","modified_gmt":"2025-08-29T10:14:33","slug":"proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe","status":"publish","type":"page","link":"https:\/\/computaex.es\/en\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/","title":{"rendered":"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE"},"content":{"rendered":"<div class=\"field field-name-field-proy-investigadores field-type-text-long field-label-above\">\n<div class=\"field-label\" style=\"text-align: justify;\"><strong>Researchers:\u00a0<\/strong><\/div>\n<div class=\"field-items\" style=\"text-align: justify;\">\n<div class=\"field-item even\">\n<ul>\n<li><strong>Edilberto S\u00e1nchez Gonz\u00e1lez<\/strong>.<\/li>\n<li><strong>Francisco Castej\u00f3n Maga\u00f1a<\/strong>.<\/li>\n<li><strong>Iv\u00e1n Calvo Rubio<\/strong>.<\/li>\n<li>Pertenecientes a la Unidad de Teor\u00eda del Laboratorio Nacional de Fusi\u00f3n del\u00a0<a href=\"http:\/\/www.ciemat.es\/\">CIEMAT<\/a>.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-descripcion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Description:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>La actividad se centra en la simulaci\u00f3n detallada de turbulencia en plasmas. Se enmarca dentro de dos proyectos financiados por el\u00a0<a href=\"http:\/\/www.micinn.es\/\" target=\"_blank\" rel=\"noopener\">Ministerio de Ciencia e Innovaci\u00f3n<\/a>, dedicados al desarrollo de m\u00e9todos cin\u00e9ticos para el estudio de plasmas confinados magn\u00e9ticamente, y a la investigaci\u00f3n de la influencia de los flujos globales y su topolog\u00eda en el transporte de plasmas turbulentos, respectivamente.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objectives:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Estudios de validaci\u00f3n y comparaci\u00f3n con otros c\u00f3digos similares, como TORB.<\/li>\n<li>Estudio de inestabilidades en el stellarator TJ-II en r\u00e9gimen lineal.<\/li>\n<li>Estudio del transporte de impurezas en un ambiente de turbulencia desarrollada, con flujos zonales.<\/li>\n<li>Estudio de la topolog\u00eda de flujos globales de origen turbulento en plasmas.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-metodologia field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Metodolog\u00eda:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<p>EUTERPE es un c\u00f3digo girocin\u00e9tico de tipo particle-in-cell (PIC), que resuelve las ecuaciones girocin\u00e9ticas discretizando la funci\u00f3n de distribuci\u00f3n por medio de marcadores. Se usa la aproximaci\u00f3n delta-f para reducir el ruido num\u00e9rico asociado a la discretizaci\u00f3n y los recursos computacionales necesarios. Una simulaci\u00f3n arranca de un estado de equilibrio calculado por el c\u00f3digo VMEC y hace evolucionar el potencial electrost\u00e1tico de forma autoconsistente, manteniendo fijo el campo magn\u00e9tico. Se usan t\u00e9cnicas de elementos finitos para calcular el potencial electrost\u00e1tico. El espacio f\u00edsico se divide en secciones toroidales, cada una de las cuales es controlada por un procesador, que hace evolucionar la posici\u00f3n y velocidad de los marcadores en esa secci\u00f3n. Se usa el API Message passing Interface (<strong>MPI<\/strong>) para coordinar los c\u00e1lculos y colectar los resultados de todos los procesadores.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-objetivos-alcanzados field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Objetivos alcanzados:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li>Se han llevado a cabo simulaciones para estudiar la dependencia de la calidad de las simulaciones no lineales realizadas con EUTERPE con par\u00e1metros de entrada como paso de tiempo del integrador, n\u00famero de marcadores y n\u00famero de nodos en la malla espacial. Se han estudiado inestabilidades ITG en el stellarator TJ-II a trav\u00e9s de simulaciones en r\u00e9gimen lineal en la configuraci\u00f3n est\u00e1ndar (100_44_64), para plamas con \\beta = 0%. Se han caracterizado las tasas de crecimiento de estas inestabilidades en esta configuraci\u00f3n.<\/li>\n<li>Se ha estudiado el confinamiento de impurezas en plasmas turbulentos en simulaciones en geometr\u00eda cil\u00edndrica usando perfiles de densidad y temperatura similares a los medios experimentales en el stellarator W7AS en modos de alto confinamiento (IC). Se encontraron inestabilidades num\u00e9ricas que han impedido avanzar en estos reg\u00edmenes.<\/li>\n<li>Para el estudio de la topolog\u00eda de flujos turbulentos, se han realizado simulaciones lineales en geometr\u00eda cil\u00edndrica usando un perfil de transformada rotacional de tipo tokamak. Cambiando los perfiles de densidad y temperatura se han encontrado reg\u00edmenes con diferentes grados de inestabilidad ITG y diferentes espectros, que posteriormente ser\u00e1n an\u00e1lizados en el r\u00e9gimen no lineal y caracterizados desde el punto de vista topol\u00f3gico.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-field-proy-financiacion field-type-text-long field-label-above\" style=\"text-align: justify;\">\n<div class=\"field-label\"><strong>Sources of funding:\u00a0<\/strong><\/div>\n<div class=\"field-items\">\n<div class=\"field-item even\">\n<ul>\n<li><a href=\"http:\/\/www.micinn.es\/\">Ministerio de Ciencia e Innovaci\u00f3n<\/a>.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"field field-name-taxonomy-vocabulary-4 field-type-taxonomy-term-reference field-label-hidden\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Investigadores:\u00a0 Edilberto S\u00e1nchez Gonz\u00e1lez. Francisco Castej\u00f3n Maga\u00f1a. Iv\u00e1n Calvo Rubio. Pertenecientes a la Unidad de Teor\u00eda del Laboratorio Nacional de Fusi\u00f3n del\u00a0CIEMAT. Descripci\u00f3n:\u00a0 La actividad se centra en la simulaci\u00f3n &#8230;<\/p>","protected":false},"author":1,"featured_media":0,"parent":9950,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[103,81],"tags":[],"class_list":["post-2683","page","type-page","status-publish","hentry","category-ciencias-de-la-vida","category-proyectos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"og:description\" content=\"Investigadores:\u00a0 Edilberto S\u00e1nchez Gonz\u00e1lez. Francisco Castej\u00f3n Maga\u00f1a. Iv\u00e1n Calvo Rubio. Pertenecientes a la Unidad de Teor\u00eda del Laboratorio Nacional de Fusi\u00f3n del\u00a0CIEMAT. Descripci\u00f3n:\u00a0 La actividad se centra en la simulaci\u00f3n ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/computaex.es\/en\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/\" \/>\n<meta property=\"og:site_name\" content=\"Fundaci\u00f3n COMPUTAEX\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/m.facebook.com\/computaex\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-29T10:14:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"403\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@computaex\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\\\/\",\"name\":\"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\"},\"datePublished\":\"2024-04-11T07:54:35+00:00\",\"dateModified\":\"2025-08-29T10:14:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/computaex.es\\\/proyectos\\\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\\\/\\\/computaex.eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proyectos\",\"item\":\"http:\\\/\\\/computaex.eu\\\/en\\\/proyectos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#website\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"name\":\"Fundaci\u00f3n COMPUTAEX\",\"description\":\"COMPUTAEX\",\"publisher\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/computaex.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#organization\",\"name\":\"COMPUTAEX\",\"url\":\"http:\\\/\\\/computaex.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/computaex.es\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/cropped-COMPUTAEX_transparente-scaled-1.png\",\"width\":2560,\"height\":970,\"caption\":\"COMPUTAEX\"},\"image\":{\"@id\":\"http:\\\/\\\/computaex.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/m.facebook.com\\\/computaex\\\/\",\"https:\\\/\\\/x.com\\\/computaex\",\"https:\\\/\\\/es.linkedin.com\\\/company\\\/cenits\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/computaex.es\/en\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/","og_locale":"en_US","og_type":"article","og_title":"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX","og_description":"Investigadores:\u00a0 Edilberto S\u00e1nchez Gonz\u00e1lez. Francisco Castej\u00f3n Maga\u00f1a. Iv\u00e1n Calvo Rubio. Pertenecientes a la Unidad de Teor\u00eda del Laboratorio Nacional de Fusi\u00f3n del\u00a0CIEMAT. Descripci\u00f3n:\u00a0 La actividad se centra en la simulaci\u00f3n ...","og_url":"https:\/\/computaex.es\/en\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/","og_site_name":"Fundaci\u00f3n COMPUTAEX","article_publisher":"https:\/\/m.facebook.com\/computaex\/","article_modified_time":"2025-08-29T10:14:33+00:00","og_image":[{"width":1024,"height":403,"url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/08\/COMPUTAEX.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@computaex","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/computaex.es\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/","url":"https:\/\/computaex.es\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/","name":"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE - Fundaci\u00f3n COMPUTAEX","isPartOf":{"@id":"http:\/\/computaex.es\/#website"},"datePublished":"2024-04-11T07:54:35+00:00","dateModified":"2025-08-29T10:14:33+00:00","breadcrumb":{"@id":"https:\/\/computaex.es\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/computaex.es\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/computaex.es\/proyectos\/proyecto-simulaciones-girocineticas-globales-de-plasmas-de-fusion-con-euterpe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/computaex.eu\/"},{"@type":"ListItem","position":2,"name":"Proyectos","item":"http:\/\/computaex.eu\/en\/proyectos\/"},{"@type":"ListItem","position":3,"name":"Simulaciones girocin\u00e9ticas globales de plasmas de fusi\u00f3n con EUTERPE"}]},{"@type":"WebSite","@id":"http:\/\/computaex.es\/#website","url":"http:\/\/computaex.es\/","name":"COMPUTAEX Foundation","description":"COMPUTAEX","publisher":{"@id":"http:\/\/computaex.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/computaex.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"http:\/\/computaex.es\/#organization","name":"COMPUTAEX","url":"http:\/\/computaex.es\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/","url":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","contentUrl":"https:\/\/computaex.es\/wp-content\/uploads\/2025\/05\/cropped-COMPUTAEX_transparente-scaled-1.png","width":2560,"height":970,"caption":"COMPUTAEX"},"image":{"@id":"http:\/\/computaex.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/m.facebook.com\/computaex\/","https:\/\/x.com\/computaex","https:\/\/es.linkedin.com\/company\/cenits"]}]}},"_links":{"self":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/comments?post=2683"}],"version-history":[{"count":4,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2683\/revisions"}],"predecessor-version":[{"id":8611,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/2683\/revisions\/8611"}],"up":[{"embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/pages\/9950"}],"wp:attachment":[{"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/media?parent=2683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/categories?post=2683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/computaex.es\/en\/wp-json\/wp\/v2\/tags?post=2683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}